{"id":68,"count":1,"description":"","link":"https:\/\/xyzcivil.com\/blog\/tag\/asheville-demand-modeling\/","name":"asheville demand modeling","slug":"asheville-demand-modeling","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/xyzcivil.com\/blog\/wp-json\/wp\/v2\/tags\/68"}],"collection":[{"href":"https:\/\/xyzcivil.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/xyzcivil.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/xyzcivil.com\/blog\/wp-json\/wp\/v2\/posts?tags=68"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}